{"id":6372,"date":"2023-09-21T16:49:55","date_gmt":"2023-09-21T16:49:55","guid":{"rendered":"https:\/\/nemoceans.com\/index.php\/nachrichten\/"},"modified":"2026-02-12T15:04:14","modified_gmt":"2026-02-12T15:04:14","slug":"nachrichten","status":"publish","type":"page","link":"https:\/\/nemocean.de\/index.php\/nachrichten\/","title":{"rendered":"News"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6372\" class=\"elementor elementor-6372\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d77eafe e-flex e-con-boxed e-con e-parent\" data-id=\"d77eafe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/nemocean.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Rayos-de-sol.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-00c0c25 elementor-widget elementor-widget-image\" data-id=\"00c0c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/elementor\/thumbs\/Nemocean-Icon_RGB-qhq6431j8kckfo14bbf6gpa5r3vqtkz1k3y38jtod0.png\" title=\"Nemocean Icon_RGB\" alt=\"Nemocean Icon_RGB\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af2883a elementor-widget elementor-widget-spacer\" data-id=\"af2883a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbc1293 elementor-widget elementor-widget-heading\" data-id=\"dbc1293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">News &amp; Trends<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f0694a elementor-widget elementor-widget-spacer\" data-id=\"9f0694a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b0395f elementor-widget elementor-widget-heading\" data-id=\"0b0395f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Willkommen auf unserer News Seite, auf der wir Ihnen regelm\u00e4\u00dfig relevante Artikel, Kundenerfahrungen und Einblicke aus Mallorca und der ganzen Welt pr\u00e4sentieren. Hier finden Sie bewegende Geschichten, bedeutsame Momente und wertvolle Informationen aus unserem Alltag. Erhalten Sie Informationen zu Themen wie Trauer, Abschied, Gedenken und Seebestattungen sowie Eindr\u00fccke \u00fcber die Sch\u00f6nheit der mallorquinischen K\u00fcste und Natur.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52832cba e-con-full e-flex e-con e-parent\" data-id=\"52832cba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12aece91 elementor-widget elementor-widget-heading\" data-id=\"12aece91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Neueste Nachrichten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-767f6e5 elementor-widget elementor-widget-spacer\" data-id=\"767f6e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36441977 elementor-widget elementor-widget-taxonomy-filter\" data-id=\"36441977\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;selected_element&quot;:&quot;6574752&quot;,&quot;taxonomy&quot;:&quot;category&quot;,&quot;horizontal_scroll&quot;:&quot;enable&quot;,&quot;item_alignment_horizontal_mobile&quot;:&quot;start&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;multiple_selection&quot;:&quot;no&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"taxonomy-filter.default\">\n\t\t\t\t\t\t\t<search class=\"e-filter\" role=\"search\" data-base-url=\"https:\/\/nemocean.de\/\" data-page-num=\"1\">\n\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"entdecken\" aria-pressed=\"false\">Entdecken<\/button>\n\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"kooperationen\" aria-pressed=\"false\">Kooperationen<\/button>\n\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"medien\" aria-pressed=\"false\">Medien<\/button>\n\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"nemocean-de\" aria-pressed=\"false\">Nemocean<\/button>\n\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"nemocean\" aria-pressed=\"false\">Nemocean<\/button>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"__all\" aria-pressed=\"true\">\n\t\t\t\tAlle\t\t\t<\/button>\n\t\t\t\t\t<\/search>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8223727 elementor-widget elementor-widget-spacer\" data-id=\"8223727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6574752 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"6574752\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:3873,&quot;masonry&quot;:&quot;yes&quot;,&quot;pagination_type&quot;:&quot;load_more_on_click&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-3873\">.elementor-3873 .elementor-element.elementor-element-7ab1d796{--display:flex;--min-height:300px;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:10px 10px;--row-gap:10px;--column-gap:10px;--border-radius:20px 20px 20px 20px;box-shadow:0px 4px 44px 0px rgba(0, 0, 0, 0.1);--margin-top:0%;--margin-bottom:5%;--margin-left:0%;--margin-right:0%;--padding-top:20px;--padding-bottom:55px;--padding-left:20px;--padding-right:20px;}.elementor-3873 .elementor-element.elementor-element-7ab1d796:hover{box-shadow:0px 2px 25px 0px rgba(0, 0, 0, 0.2);}.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );text-transform:var( --e-global-typography-text-text-transform );font-style:var( --e-global-typography-text-font-style );text-decoration:var( --e-global-typography-text-text-decoration );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-3d2e8ac5 img{width:100%;height:100%;object-fit:cover;object-position:center center;filter:brightness( 100% ) contrast( 100% ) saturate( 100% ) blur( 0px ) hue-rotate( 0deg );transition-duration:0.3s;}.elementor-3873 .elementor-element.elementor-element-3d2e8ac5:hover img{filter:brightness( 105% ) contrast( 100% ) saturate( 105% ) blur( 0px ) hue-rotate( 0deg );}.elementor-3873 .elementor-element.elementor-element-3d2e8ac5{width:100%;max-width:100%;}.elementor-3873 .elementor-element.elementor-element-402af5db{--display:flex;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--align-items:center;--gap:14px 14px;--row-gap:14px;--column-gap:14px;--margin-top:15px;--margin-bottom:15px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-size:var( --e-global-typography-primary-font-size );font-weight:var( --e-global-typography-primary-font-weight );text-transform:var( --e-global-typography-primary-text-transform );font-style:var( --e-global-typography-primary-font-style );text-decoration:var( --e-global-typography-primary-text-decoration );line-height:var( --e-global-typography-primary-line-height );letter-spacing:var( --e-global-typography-primary-letter-spacing );color:var( --e-global-color-primary );}.elementor-3873 .elementor-element.elementor-element-481a21f7 .elementor-heading-title{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-size:var( --e-global-typography-accent-font-size );font-weight:var( --e-global-typography-accent-font-weight );text-transform:var( --e-global-typography-accent-text-transform );font-style:var( --e-global-typography-accent-font-style );text-decoration:var( --e-global-typography-accent-text-decoration );line-height:var( --e-global-typography-accent-line-height );letter-spacing:var( --e-global-typography-accent-letter-spacing );color:#FFFFFF;}.elementor-3873 .elementor-element.elementor-element-481a21f7{padding:3px 12px 2px 12px;background-color:var( --e-global-color-primary );border-radius:30px 30px 30px 30px;}.elementor-3873 .elementor-element.elementor-element-359f53ea .elementor-heading-title{font-family:\"Questrial\", Sans-serif;font-size:18px;font-weight:600;text-transform:uppercase;font-style:normal;text-decoration:none;line-height:1.5em;letter-spacing:-0.01em;word-spacing:0em;color:#8D8D8D;}.elementor-3873 .elementor-element.elementor-element-359f53ea{padding:6px 0px 6px 0px;}.elementor-widget-theme-post-title .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-size:var( --e-global-typography-primary-font-size );font-weight:var( --e-global-typography-primary-font-weight );text-transform:var( --e-global-typography-primary-text-transform );font-style:var( --e-global-typography-primary-font-style );text-decoration:var( --e-global-typography-primary-text-decoration );line-height:var( --e-global-typography-primary-line-height );letter-spacing:var( --e-global-typography-primary-letter-spacing );color:var( --e-global-color-primary );}.elementor-3873 .elementor-element.elementor-element-62a5bc59 .elementor-heading-title{font-size:20px;font-weight:600;text-transform:none;line-height:1.5em;color:#181818;}.elementor-widget-theme-post-excerpt{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );text-transform:var( --e-global-typography-text-text-transform );font-style:var( --e-global-typography-text-font-style );text-decoration:var( --e-global-typography-text-text-decoration );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );color:var( --e-global-color-text );}@media(max-width:1024px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-3d2e8ac5 img{height:200px;}.elementor-3873 .elementor-element.elementor-element-402af5db{--justify-content:space-between;}.elementor-widget-heading .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );letter-spacing:var( --e-global-typography-primary-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-481a21f7 .elementor-heading-title{font-size:var( --e-global-typography-accent-font-size );line-height:var( --e-global-typography-accent-line-height );letter-spacing:var( --e-global-typography-accent-letter-spacing );}.elementor-widget-theme-post-title .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );letter-spacing:var( --e-global-typography-primary-letter-spacing );}.elementor-widget-theme-post-excerpt{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}}@media(max-width:767px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-3d2e8ac5 img{height:168px;}.elementor-3873 .elementor-element.elementor-element-402af5db{--justify-content:flex-start;}.elementor-widget-heading .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );letter-spacing:var( --e-global-typography-primary-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-481a21f7 .elementor-heading-title{font-size:var( --e-global-typography-accent-font-size );line-height:var( --e-global-typography-accent-line-height );letter-spacing:var( --e-global-typography-accent-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-481a21f7{padding:1px 12px 1px 12px;}.elementor-3873 .elementor-element.elementor-element-359f53ea .elementor-heading-title{font-size:17px;}.elementor-widget-theme-post-title .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );letter-spacing:var( --e-global-typography-primary-letter-spacing );}.elementor-3873 .elementor-element.elementor-element-62a5bc59{text-align:start;}.elementor-widget-theme-post-excerpt{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-9303 post-9303 post type-post status-publish format-standard has-post-thumbnail hentry category-nemocean-de\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/transport-einer-urne-nach-spanien-per-flugzeug-was-sie-wissen-sollten\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1439\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-scaled.webp\" class=\"attachment-full size-full wp-image-9304\" alt=\"Transport einer Urne nach Spanien per Flugzeug Was Sie wissen sollten\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-scaled.webp 2560w, https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-300x169.webp 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-1024x576.webp 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-768x432.webp 768w, https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-1536x864.webp 1536w, https:\/\/nemocean.de\/wp-content\/uploads\/2026\/01\/Transport-einer-Urne-nach-Spanien-per-Flugzeug-Was-Sie-wissen-sollten-2048x1151.webp 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Nemocean<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">29 Jan. 2026<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Transport einer Urne nach Spanien per Flugzeug: Was Sie wissen sollten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Der Transport einer Urne nach Spanien bereitet vielen Familien Sorgen, die eine Beisetzung oder eine Zeremonie auf den Inseln durchf\u00fchren m\u00f6chten. Besonders f\u00fcr deutsche Familien...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-9290 post-9290 post type-post status-publish format-standard has-post-thumbnail hentry category-nemocean\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/beruehmte-persoenlichkeiten-von-denen-sie-nicht-wussten-dass-sie-auf-see-bestattet-wurden-band-1\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1439\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-scaled.png\" class=\"attachment-full size-full wp-image-9291\" alt=\"Ber\u00fchmte Pers\u00f6nlichkeiten dass sie auf See bestattet wurden\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-scaled.png 2560w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-300x169.png 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-1024x576.png 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-768x432.png 768w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-1536x864.png 1536w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/12\/7-2048x1151.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Nemocean<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">9 Dez. 2025<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ber\u00fchmte Pers\u00f6nlichkeiten, von denen Sie nicht wussten, dass sie auf See bestattet wurden \u2013 Band 1<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Wenn wir an ber\u00fchmte Pers\u00f6nlichkeiten und ihre letzte Ruhest\u00e4tte denken, stellen wir uns oft pr\u00e4chtige Friedh\u00f6fe, Marmortafeln oder Mausoleen vor, die Besucher anziehen. Doch f\u00fcr...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-9240 post-9240 post type-post status-publish format-standard has-post-thumbnail hentry category-entdecken\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/die-geschichte-von-seebestattungen\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1366\" height=\"768\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2025\/08\/WHAT-DO-YOU-KNOW-ABOUT-BURIALS-AT-SEA3.png\" class=\"attachment-full size-full wp-image-9241\" alt=\"\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2025\/08\/WHAT-DO-YOU-KNOW-ABOUT-BURIALS-AT-SEA3.png 1366w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/08\/WHAT-DO-YOU-KNOW-ABOUT-BURIALS-AT-SEA3-300x169.png 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/08\/WHAT-DO-YOU-KNOW-ABOUT-BURIALS-AT-SEA3-1024x576.png 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2025\/08\/WHAT-DO-YOU-KNOW-ABOUT-BURIALS-AT-SEA3-768x432.png 768w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Entdecken<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">8 Aug. 2025<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Die Geschichte von Seebestattungen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Eine zeitlose Ehrung in verschiedenen Kulturen Von Polynesien bis Skandinavien waren Seebestattungen seit jeher bedeutungsvolle Abschiedsrituale, gepr\u00e4gt von verschiedenen Kulturen und ihrer Verbindung zum Ozean....\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-8961 post-8961 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/partner-westend-bestattungen-berlin\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/08\/titelbild-westend-bestattungen.jpg\" class=\"attachment-full size-full wp-image-8962\" alt=\"westend bestattungen\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/08\/titelbild-westend-bestattungen.jpg 1000w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/08\/titelbild-westend-bestattungen-300x225.jpg 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/08\/titelbild-westend-bestattungen-768x576.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">16 Aug. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;Westend Bestattungen&#8220; aus Berlin<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Erdbestattung und Feuerbestattung \u2013 Ihre verl\u00e4sslichen Partner in Berlin Bei Westend Bestattungen in Berlin Charlottenburg stehen Erdbestattungen und Feuerbestattungen im Mittelpunkt unserer Dienstleistungen. Als erfahrener...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-8912 post-8912 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/partner-bentzien-brocksiepe-lunen-dortmund\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"429\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/06\/cnt_eheleute-bentzien.jpeg\" class=\"attachment-full size-full wp-image-8915\" alt=\"\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/06\/cnt_eheleute-bentzien.jpeg 640w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/06\/cnt_eheleute-bentzien-300x201.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">5 Juni 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;Bentzien &#038; Brocksiepe&#8220; aus L\u00fcnen und Dortmund<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Nemocean begr\u00fc\u00dft eine neue Partnerschaft mit dem Bestattungshaus BENTZIEN &amp; BROCKSIEPE. Im folgenden stellt sich der Partner aus L\u00fcnen und Dortmund vor: &nbsp; &nbsp; \u00dcber...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7836 post-7836 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/partner-kl-bestattungen-aus-berlin\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"165\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/kl-bestattungen-wolfram2.jpg\" class=\"attachment-full size-full wp-image-7854\" alt=\"Funeral Director from KL-Bestattungen Wolfram\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">4 Apr. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;KL-Bestattungen&#8220; aus Berlin<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Wir freuen uns die in Berlin, Brandenburg ans\u00e4ssige KL-Bestattungen unter Leitung von Herrn Wolfgang Kl\u00fcgel, als Kooperationspartner begr\u00fc\u00dfen und empfehlen zu d\u00fcrfen. &nbsp; Im Folgenden...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7813 post-7813 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/kooperation-mit-in-memoria-bestattungen\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1968\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-scaled.jpg\" class=\"attachment-full size-full wp-image-9184\" alt=\"In Memoria Bestattungen\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-scaled.jpg 2560w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-300x231.jpg 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-1024x787.jpg 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-768x590.jpg 768w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-1536x1181.jpg 1536w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/04\/Sabrina-und-Thomas-2048x1574.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">3 Apr. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;In Memoria Bestattungen&#8220; aus der Schweiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Wir freuen uns die in Uetendorf im schweizer Kanton Bern ans\u00e4ssige In Memoria Bestattungen GmbH als neuen Kooperationspartner begr\u00fc\u00dfen und empfehlen zu d\u00fcrfen. Im Folgenden...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7711 post-7711 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen tag-luctum tag-schweiz\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/partner-luctum-aus-der-schweiz\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"709\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Claudia_Moldovanyi_home3.png\" class=\"attachment-full size-full wp-image-7706\" alt=\"Claudia Moldovanyi\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Claudia_Moldovanyi_home3.png 723w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Claudia_Moldovanyi_home3-300x294.png 300w\" sizes=\"(max-width: 723px) 100vw, 723px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">21 Feb. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;Luctum&#8220; aus der Schweiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Was wollen und k\u00f6nnen wir tun? F\u00fcr Sie da zu sein! Die Seele eines Menschen w\u00fcrdigen, sie im Todesfall mit Respekt und Einf\u00fchlsamkeit begegnen, mit...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7693 post-7693 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen tag-partner tag-schweiz\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/partner-bestattungen-nisio-aus-der-schweiz\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1479\" height=\"952\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Logo-NISIO-Braun_page-0001-725x1024v3.jpg\" class=\"attachment-full size-full wp-image-7722\" alt=\"NISIO Funeral services Switzerland Logo\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Logo-NISIO-Braun_page-0001-725x1024v3.jpg 1479w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Logo-NISIO-Braun_page-0001-725x1024v3-300x193.jpg 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Logo-NISIO-Braun_page-0001-725x1024v3-1024x659.jpg 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Logo-NISIO-Braun_page-0001-725x1024v3-768x494.jpg 768w\" sizes=\"(max-width: 1479px) 100vw, 1479px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">19 Feb. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;Bestattungen Nisio&#8220; aus der Schweiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Das Team Unser Unternehmen steht f\u00fcr Einf\u00fchlungsverm\u00f6gen, Diskretion und Professionalit\u00e4t in allen Bereichen des Bestattungswesens. Alessandro Fattorini und seine erfahrenen Mitarbeiter stehen Ihnen in einer...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7669 post-7669 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen tag-partner tag-schweiz\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/partner-bestattungsinstitut-rea-aus-der-schweiz\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1167\" height=\"349\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Banner_rea_ag.JPG\" class=\"attachment-full size-full wp-image-7666\" alt=\"Bestattungsinstitut Rea\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Banner_rea_ag.JPG 1167w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Banner_rea_ag-300x90.jpg 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Banner_rea_ag-1024x306.jpg 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/02\/Banner_rea_ag-768x230.jpg 768w\" sizes=\"(max-width: 1167px) 100vw, 1167px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">19 Feb. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;Bestattungsinstitut Rea&#8220; aus der Schweiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>&#8222;Bestattungsinstitut Rea&#8220; aus der Schweiz spricht mit uns: Und pl\u00f6tzlich ist alles anders\u2026 Trotz des Wissens um unsere Sterblichkeit trifft uns der Tod eines nahestehenden...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7544 post-7544 post type-post status-publish format-standard has-post-thumbnail hentry category-nemocean-de tag-auswartiges-amt tag-deutsches-konsulat tag-deutsches-konsulat-palma tag-seebestattung-mallorca\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/deutsches-konsulat-partnerschaft-fur-seebestattungen-auf-mallorca\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"510\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/Deutsches-Kon-1.jpg\" class=\"attachment-full size-full wp-image-7546\" alt=\"Deutsches Konsulat\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/Deutsches-Kon-1.jpg 680w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/Deutsches-Kon-1-300x225.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Nemocean<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">22 Jan. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Deutsches Konsulat: Partner f\u00fcr Seebestattungen auf Mallorca<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Nemocean, der f\u00fchrende Anbieter f\u00fcr Premium- und besondere Seebestattungen auf Mallorca, ist k\u00fcrzlich eine bahnbrechende Partnerschaft mit dem deutschen Konsulat eingegangen. Diese Zusammenarbeit geht jedoch...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3873\" class=\"elementor elementor-3873 e-loop-item e-loop-item-7506 post-7506 post type-post status-publish format-standard has-post-thumbnail hentry category-kooperationen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-7ab1d796 e-con-full e-flex e-con e-parent\" data-id=\"7ab1d796\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/nemocean.de\/index.php\/koop-partner-muenchner-pietaet\/\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2e8ac5 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"3d2e8ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1169\" height=\"1035\" src=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/IMG_7959.jpg\" class=\"attachment-full size-full wp-image-7499\" alt=\"M\u00fcnchner PIet\u00e4t\" srcset=\"https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/IMG_7959.jpg 1169w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/IMG_7959-300x266.jpg 300w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/IMG_7959-1024x907.jpg 1024w, https:\/\/nemocean.de\/wp-content\/uploads\/2024\/01\/IMG_7959-768x680.jpg 768w\" sizes=\"(max-width: 1169px) 100vw, 1169px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402af5db e-con-full e-flex e-con e-child\" data-id=\"402af5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481a21f7 elementor-widget elementor-widget-heading\" data-id=\"481a21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Kooperationen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359f53ea elementor-widget elementor-widget-heading\" data-id=\"359f53ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">8 Jan. 2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a5bc59 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"62a5bc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Partner &#8222;M\u00fcnchner Piet\u00e4t&#8220;<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2fbae elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"5d2fbae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t\t<p>Die M\u00fcnchner Piet\u00e4t ist ein frauengef\u00fchrtes, junges Bestattungsunternehmen aus M\u00fcnchen. Gemeinsam mit unserem Bestatter der auf 18 Jahre Berufserfahrung zur\u00fcckblicken kann, sowie dem gesamten Team...\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-spinner\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M304 48c0 26.51-21.49 48-48 48s-48-21.49-48-48 21.49-48 48-48 48 21.49 48 48zm-48 368c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48zm208-208c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48zM96 256c0-26.51-21.49-48-48-48S0 229.49 0 256s21.49 48 48 48 48-21.49 48-48zm12.922 99.078c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48c0-26.509-21.491-48-48-48zm294.156 0c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48c0-26.509-21.49-48-48-48zM108.922 60.922c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.491-48-48-48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"2\" data-next-page=\"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/pages\/6372\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"e-loop__load-more elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr laden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"e-load-more-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a03ae43 e-flex e-con-boxed e-con e-parent\" data-id=\"1a03ae43\" data-element_type=\"container\" data-e-type=\"container\" id=\"subscribe\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-745bdbd3 e-flex e-con-boxed e-con e-child\" data-id=\"745bdbd3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4494731a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4494731a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abonnieren Sie unseren Newsletter und bleiben Sie auf dem Laufenden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11fa0811 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"11fa0811\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Weiter&quot;,&quot;step_previous_label&quot;:&quot;Vorheriges&quot;,&quot;button_width&quot;:&quot;40&quot;,&quot;button_width_tablet&quot;:&quot;40&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Newsletter Subscription\" aria-label=\"Newsletter Subscription\" novalidate=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"6372\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"11fa0811\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"News - Nemoceans\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"6372\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-60\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tIhr Name\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Ihren Namen\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-60 elementor-md-60 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tIhre E-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Ihre E-Mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-40 e-form__buttons elementor-md-40\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abbonieren<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>News &amp; Trends Willkommen auf unserer News Seite, auf der wir Ihnen regelm\u00e4\u00dfig relevante Artikel, Kundenerfahrungen und Einblicke aus Mallorca und der ganzen Welt pr\u00e4sentieren. Hier finden Sie bewegende Geschichten, bedeutsame Momente und wertvolle Informationen aus unserem Alltag. Erhalten Sie Informationen zu Themen wie Trauer, Abschied, Gedenken und Seebestattungen sowie Eindr\u00fccke \u00fcber die Sch\u00f6nheit der [&hellip;]<\/p>\n","protected":false},"author":990002,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6372","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/pages\/6372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/users\/990002"}],"replies":[{"embeddable":true,"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/comments?post=6372"}],"version-history":[{"count":3,"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/pages\/6372\/revisions"}],"predecessor-version":[{"id":9317,"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/pages\/6372\/revisions\/9317"}],"wp:attachment":[{"href":"https:\/\/nemocean.de\/index.php\/wp-json\/wp\/v2\/media?parent=6372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}